{"id":840,"date":"2015-03-20T12:28:51","date_gmt":"2015-03-20T16:28:51","guid":{"rendered":"http:\/\/www.musee-mccord-stewart.ca\/?page_id=840"},"modified":"2026-06-18T09:56:09","modified_gmt":"2026-06-18T13:56:09","slug":"admission-fees","status":"publish","type":"page","link":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/","title":{"rendered":"Admission Fees"},"content":{"rendered":"<p><strong>Buy your tickets online and save $2<\/strong><sup>1<\/sup><strong>!<\/strong><\/p>\n<p><a class=\"cta\" title=\"\" href=\"https:\/\/musee-mccord-stewart.logikpos.ca\/\" target=\"_blank\" rel=\"noopener\">Buy tickets<i class=\"arrow-right-thickicon-\"><\/i><\/a><\/p>\n<table style=\"height: 348px; width: 30.5%;\" width=\"434\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 24px;\">General Admission (Adult)<\/td>\n<td style=\"width: 66.7447%; height: 24px;\"><a href=\"https:\/\/musee-mccord-stewart.logikpos.ca\/\">$20 online<\/a> | +$2 at the door<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 24px;\">Senior (65+)<\/td>\n<td style=\"width: 66.7447%; height: 24px;\"><a href=\"https:\/\/musee-mccord-stewart.logikpos.ca\/\">$19 online<\/a> | +$2 at the door<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 26px;\">Student<sup>2<\/sup> (18-30)<\/td>\n<td style=\"width: 66.7447%; height: 26px;\"><a href=\"https:\/\/musee-mccord-stewart.logikpos.ca\/\">$15 online<\/a> | +$2 at the door<\/td>\n<\/tr>\n<tr style=\"height: 51px;\">\n<td style=\"width: 31.3817%; height: 51px;\">Teen<sup>3 <\/sup>(13-17)<\/td>\n<td style=\"width: 66.7447%; height: 51px;\">Free (not applicable to organized groups)<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 26px;\">Child<sup>4<\/sup> (12 and under)<\/td>\n<td style=\"width: 66.7447%; height: 26px;\">Free (not applicable to organized groups)<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 48px;\">Museum Member<\/td>\n<td style=\"width: 66.7447%; height: 48px;\">Free<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 31.3817%; height: 50px;\">Members of Indigenous communities<sup>5<\/sup><\/td>\n<td style=\"width: 66.7447%; height: 50px;\">Free<\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 31.3817%; height: 47px;\"><strong>Wednesday evenings<\/strong><sup>6<\/sup> (starting at 5 p.m.)<\/td>\n<td style=\"width: 66.7447%; height: 47px;\">Free: <strong><a href=\"https:\/\/www.musee-mccord-stewart.ca\/en\/exhibitions\/indigenous-voices-of-today\/\"><em>Indigenous Voices of Today<\/em><\/a><\/strong><br \/>\n$10 online | +$2 at the door:<strong><em><a title=\"On the Menu\" href=\"https:\/\/www.musee-mccord-stewart.ca\/en\/exhibitions\/on-the-menu-montreal-restaurant-story\/\">On the Menu \u2013 Montreal: A Restaurant Story<\/a><\/em><\/strong>,\u00a0<a href=\"https:\/\/www.musee-mccord-stewart.ca\/en\/exhibitions\/montreal-1976-an-olympic-feat\/\"><strong><em>Montreal 1976: An Olympic Feat<\/em><\/strong><\/a> and <em><strong><a href=\"https:\/\/www.musee-mccord-stewart.ca\/en\/exhibitions\/celine-in-dior-dazzling-moment\/\">C\u00e9line in Dior: A Dazzling Moment<\/a><\/strong><\/em><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 31.3817%;\"><strong>First Sunday of the month<\/strong><sup>7<\/sup><\/td>\n<td style=\"width: 66.7447%;\">Monthly \u201cPay What You Can\u201d day (no reservation required)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>The Museum sincerely thanks <a title=\"\" href=\"https:\/\/our-impact.bmo.com\/\" target=\"_blank\" rel=\"noopener\">BMO<\/a>\u00a0for free admission on Wednesday evenings, and the <a title=\"\" href=\"https:\/\/www.jadeseve.com\/\" target=\"_blank\" rel=\"noopener\">Fondation J. A. DeS\u00e8ve<\/a> for free admission for children 12 and under, and The Rossy Foundation for free admission for teens aged 13 to 17.<\/p>\n<p>We sincerely thank the Azrieli Foundation for their generous contribution to the accessibility program on the first Sunday of every month. This support, combined with the &#8220;Pay what you can&#8221; formula, reaffirms our commitment to making culture accessible to the widest possible audience.<br \/>\n<a class=\"cta\" title=\"\" href=\"https:\/\/billets.musee-mccord-stewart.ca\/en\/\" target=\"_blank\" rel=\"noopener\">Tickets<i class=\"arrow-right-thickicon-\"><\/i><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buy your tickets online and save $21! Buy tickets General Admission (Adult) $20 online | +$2 at the door Senior (65+) $19 online | +$2 at the door Student2 (18-30) $15 online | +$2 at the door Teen3 (13-17) Free (not applicable to organized groups) Child4 (12 and under) Free (not applicable to organized groups) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-texte.php","meta":{"footnotes":""},"categories":[],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v20.11) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plan your next visit: admission fees - McCord Stewart Museum<\/title>\n<meta name=\"description\" content=\"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Admission Fees\" \/>\n<meta property=\"og:description\" content=\"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/\" \/>\n<meta property=\"og:site_name\" content=\"McCord Stewart Museum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museemccordstewart\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T13:56:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2025\/08\/mccord-stewart_planifiez-visite_2025_640x375.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.\" \/>\n<meta name=\"twitter:site\" content=\"@MuseeMcCordStew\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/\",\"url\":\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/\",\"name\":\"Plan your next visit: admission fees - McCord Stewart Museum\",\"isPartOf\":{\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#website\"},\"datePublished\":\"2015-03-20T16:28:51+00:00\",\"dateModified\":\"2026-06-18T13:56:09+00:00\",\"description\":\"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.musee-mccord-stewart.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Admission Fees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#website\",\"url\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/\",\"name\":\"McCord Stewart Museum\",\"description\":\"Our world, our stories\",\"publisher\":{\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#organization\"},\"alternateName\":\"MCS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#organization\",\"name\":\"McCord Stewart Museum\",\"alternateName\":\"MCS\",\"url\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2023\/05\/logo_museemccordstewart_horizontal_noir_slogan.svg\",\"contentUrl\":\"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2023\/05\/logo_museemccordstewart_horizontal_noir_slogan.svg\",\"width\":1,\"height\":1,\"caption\":\"McCord Stewart Museum\"},\"image\":{\"@id\":\"https:\/\/www.musee-mccord-stewart.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/museemccordstewart\",\"https:\/\/twitter.com\/MuseeMcCordStew\",\"https:\/\/instagram.com\/museemccordstewart\",\"https:\/\/www.linkedin.com\/company\/museemccordstewart\/\",\"https:\/\/www.pinterest.com\/museemccordstewart\/\",\"https:\/\/www.youtube.com\/c\/MuseeMcCordStewartMuseum\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plan your next visit: admission fees - McCord Stewart Museum","description":"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/","og_locale":"en_US","og_type":"article","og_title":"Admission Fees","og_description":"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.","og_url":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/","og_site_name":"McCord Stewart Museum","article_publisher":"https:\/\/www.facebook.com\/museemccordstewart","article_modified_time":"2026-06-18T13:56:09+00:00","og_image":[{"width":640,"height":375,"url":"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2025\/08\/mccord-stewart_planifiez-visite_2025_640x375.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.","twitter_site":"@MuseeMcCordStew","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/","url":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/","name":"Plan your next visit: admission fees - McCord Stewart Museum","isPartOf":{"@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#website"},"datePublished":"2015-03-20T16:28:51+00:00","dateModified":"2026-06-18T13:56:09+00:00","description":"The McCord Stewart Museum admission fees for all visitors. Free admission at all times for children 12 and under; and on Wednesday evening. Conditions apply.","breadcrumb":{"@id":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.musee-mccord-stewart.ca\/en\/admission-fees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.musee-mccord-stewart.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Admission Fees"}]},{"@type":"WebSite","@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#website","url":"https:\/\/www.musee-mccord-stewart.ca\/fr\/","name":"McCord Stewart Museum","description":"Our world, our stories","publisher":{"@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#organization"},"alternateName":"MCS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.musee-mccord-stewart.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#organization","name":"McCord Stewart Museum","alternateName":"MCS","url":"https:\/\/www.musee-mccord-stewart.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2023\/05\/logo_museemccordstewart_horizontal_noir_slogan.svg","contentUrl":"https:\/\/www.musee-mccord-stewart.ca\/app\/uploads\/2023\/05\/logo_museemccordstewart_horizontal_noir_slogan.svg","width":1,"height":1,"caption":"McCord Stewart Museum"},"image":{"@id":"https:\/\/www.musee-mccord-stewart.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museemccordstewart","https:\/\/twitter.com\/MuseeMcCordStew","https:\/\/instagram.com\/museemccordstewart","https:\/\/www.linkedin.com\/company\/museemccordstewart\/","https:\/\/www.pinterest.com\/museemccordstewart\/","https:\/\/www.youtube.com\/c\/MuseeMcCordStewartMuseum"]}]}},"_links":{"self":[{"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/pages\/840"}],"collection":[{"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":0,"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/pages\/840\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/media?parent=840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/categories?post=840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.musee-mccord-stewart.ca\/en\/wp-json\/wp\/v2\/tags?post=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}